{"id":4155,"date":"2021-10-01T10:00:12","date_gmt":"2021-10-01T08:00:12","guid":{"rendered":"https:\/\/dev.setupandorra.com\/\/?page_id=4155"},"modified":"2024-07-11T15:31:38","modified_gmt":"2024-07-11T13:31:38","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/setupandorra.com\/es\/politica-de-cookies\/","title":{"rendered":"POLITICA DE COOKIES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mientras naveg\u00e1is por nuestro web es posible que recopilemos informaci\u00f3n relativa al tr\u00e1fico y a patrones de visita de las p\u00e1ginas de nuestro dominio. Esta informaci\u00f3n se trata a trav\u00e9s de galletas o cookies (peque\u00f1as cantidades de informaci\u00f3n en formato texto que la p\u00e1gina env\u00eda a los ordenadores o equipos de los usuarios mientras la visitan).<br>El objetivo del uso de las galletas es personalizar el acceso a la p\u00e1gina con el prop\u00f3sito de mejorar su navegaci\u00f3n y las condiciones de funcionalidad.<br>Una galleta es un peque\u00f1o archivo de texto que se almacena en el ordenador, la tableta, el tel\u00e9fono m\u00f3vil o, en definitiva, el dispositivo que utilic\u00e9is para navegar a trav\u00e9s de internet y que puede guardar informaci\u00f3n relativa a la frecuencia con que visit\u00e1is las p\u00e1ginas web, vuestras preferencias de navegaci\u00f3n, la informaci\u00f3n que m\u00e1s os interesa y vuestros nombres de usuario, registros de productos, etc.<br>En nuestro caso, las galletas que usamos en nuestro web no recopilan informaci\u00f3n que os identifique de manera personal.<br>La responsable del tratamiento es: SET UP EXPATRIATION, S.L.U. L-711714-B &#8211; C\/ Joan Maragall, 25 1\u00ba2\u00aa &#8211; Edif. Jordi -AD500- ANDORRA LA VELLA (PRINCIPADO DE ANDORRA).<br>Para m\u00e1s informaci\u00f3n, nos pueden contactar a la siguiente direcci\u00f3n de correo electr\u00f3nico: virginiehergel@setupandorra.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>TIPO DE GALLETAS<\/strong><br>En funci\u00f3n de su naturaleza, las galletas se pueden clasificar de la siguiente manera:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Galletas de sesi\u00f3n y galletas permanentes: las primeras se eliminan al cerrar el navegador, mientras que las segundas permanecen en el equipo inform\u00e1tico.<\/li>\n\n\n\n<li>Galletas propias y galletas de terceros: las primeras pertenecen a la persona o entidad titular del web, mientras que las segundas pertenecen a un tercero.<\/li>\n\n\n\n<li><br><strong>\u00bfQu\u00e9 galletas utilizamos?<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mientras naveg\u00e1is por nuestro web es posible que recopilemos informaci\u00f3n relativa al tr\u00e1fico y a patrones de visita de las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"mention.php","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4155","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>POLITICA DE COOKIES -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setupandorra.com\/es\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POLITICA DE COOKIES -\" \/>\n<meta property=\"og:description\" content=\"Mientras naveg\u00e1is por nuestro web es posible que recopilemos informaci\u00f3n relativa al tr\u00e1fico y a patrones de visita de las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setupandorra.com\/es\/politica-de-cookies\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T13:31:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POLITICA DE COOKIES -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setupandorra.com\/es\/politica-de-cookies\/","og_locale":"es_ES","og_type":"article","og_title":"POLITICA DE COOKIES -","og_description":"Mientras naveg\u00e1is por nuestro web es posible que recopilemos informaci\u00f3n relativa al tr\u00e1fico y a patrones de visita de las [&hellip;]","og_url":"https:\/\/setupandorra.com\/es\/politica-de-cookies\/","article_modified_time":"2024-07-11T13:31:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/setupandorra.com\/es\/politica-de-cookies\/","url":"https:\/\/setupandorra.com\/es\/politica-de-cookies\/","name":"POLITICA DE COOKIES -","isPartOf":{"@id":"https:\/\/setupandorra.com\/es\/#website"},"datePublished":"2021-10-01T08:00:12+00:00","dateModified":"2024-07-11T13:31:38+00:00","breadcrumb":{"@id":"https:\/\/setupandorra.com\/es\/politica-de-cookies\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setupandorra.com\/es\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/setupandorra.com\/es\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/setupandorra.com\/es\/"},{"@type":"ListItem","position":2,"name":"POLITICA DE COOKIES"}]},{"@type":"WebSite","@id":"https:\/\/setupandorra.com\/es\/#website","url":"https:\/\/setupandorra.com\/es\/","name":"Setup Andorra","description":"","publisher":{"@id":"https:\/\/setupandorra.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setupandorra.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/setupandorra.com\/es\/#organization","name":"Setup Andorra","url":"https:\/\/setupandorra.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/setupandorra.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/setupandorra.com\/wp-content\/uploads\/2026\/02\/setup-andorra-logo.webp","contentUrl":"https:\/\/setupandorra.com\/wp-content\/uploads\/2026\/02\/setup-andorra-logo.webp","width":380,"height":202,"caption":"Setup Andorra"},"image":{"@id":"https:\/\/setupandorra.com\/es\/#\/schema\/logo\/image\/"}}]}},"spectra_custom_meta":{"_yoast_wpseo_content_score":["60","60"],"_yoast_wpseo_estimated-reading-time-minutes":["2","2"],"_yoast_wpseo_wordproof_timestamp":["",""],"_edit_lock":["1720704919:1"],"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"en\":281,\"fr\":281,\"es\":281}}"],"_edit_last":["1"],"cmplz_hide_cookiebanner":[""],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_wp_page_template":["mention.php"],"_cmplz_scanned_post":["1"],"_last_translation_edit_mode":["native-editor"],"_uag_css_file_name":["uag-css-4155.css"],"_elementor_page_assets":["a:0:{}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:10:{i:0;s:14:\"core\/paragraph\";i:1;s:9:\"core\/list\";i:2;s:14:\"core\/list-item\";i:3;s:11:\"core\/search\";i:4;s:10:\"core\/group\";i:5;s:12:\"core\/heading\";i:6;s:17:\"core\/latest-posts\";i:7;s:20:\"core\/latest-comments\";i:8;s:13:\"core\/archives\";i:9;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1784110704\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"silveradminitratorand","author_link":"https:\/\/setupandorra.com\/es\/author\/silveradminitratorand\/"},"uagb_comment_info":0,"uagb_excerpt":"Mientras naveg\u00e1is por nuestro web es posible que recopilemos informaci\u00f3n relativa al tr\u00e1fico y a patrones de visita de las [&hellip;]","_links":{"self":[{"href":"https:\/\/setupandorra.com\/es\/wp-json\/wp\/v2\/pages\/4155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setupandorra.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/setupandorra.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/setupandorra.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/setupandorra.com\/es\/wp-json\/wp\/v2\/comments?post=4155"}],"version-history":[{"count":0,"href":"https:\/\/setupandorra.com\/es\/wp-json\/wp\/v2\/pages\/4155\/revisions"}],"wp:attachment":[{"href":"https:\/\/setupandorra.com\/es\/wp-json\/wp\/v2\/media?parent=4155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}